{"id":3483,"date":"2012-12-18T13:45:09","date_gmt":"2012-12-18T11:45:09","guid":{"rendered":"http:\/\/www.microgamma.es\/blog\/?p=3483"},"modified":"2014-01-23T10:28:56","modified_gmt":"2014-01-23T08:28:56","slug":"calibracion-y-perfilacion-disponible","status":"publish","type":"post","link":"https:\/\/www.monitor-para-fotografia.com\/index.php\/2012\/12\/calibracion-y-perfilacion-disponible\/","title":{"rendered":"Calibracion y perfilacion, disponible"},"content":{"rendered":"<p>Ya tenemos disponible la nueva edici\u00f3n del libro \u00abCalibraci\u00f3n y perfilaci\u00f3n de monitores\u00bb<\/p>\n<p><a href=\"http:\/\/www.microgamma.com\/calibracion_perfilacion_monitores\/calibracion_monitores_nueva.php\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone\" alt=\"calibrar monitor\" src=\"http:\/\/www.microgamma.com\/calibracion_perfilacion_monitores\/2012\/_MG_6514_600.jpg\" width=\"485\" height=\"323\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"http:\/\/www.microgamma.com\/calibracion_perfilacion_monitores\/calibracion_monitores_nueva.php\">http:\/\/www.microgamma.com\/calibracion_perfilacion_monitores\/calibracion_monitores_nueva.php<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Introducci\u00f3n<\/p>\n<p>PARTE 1<\/p>\n<p>CAP\u00cdTULO 1<br \/>\nTeor\u00eda del color<\/p>\n<p>1.1. El espectro electromagn\u00e9tico 11<br \/>\n1.1.1 Longitud de onda 11<br \/>\n1.1.2 Espectro visible 12<br \/>\n1.1.3 Gr\u00e1ficas espectrofotom\u00e9tricas 12<br \/>\n1.1.4 Fotometr\u00eda 12<\/p>\n<p>1.2 El color 13<br \/>\n1.2.1 Color emitido: S\u00edntesis aditiva (RGB) 13<br \/>\n1.2.2 Color reflejado: S\u00edntesis substractiva (CMYK) 13<br \/>\n1.2.3 Relaci\u00f3n entre s\u00edntesis 14<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" alt=\"calibrar el monitor\" src=\"http:\/\/www.microgamma.com\/calibracion_perfilacion_monitores\/2012\/llibre_2013_06.jpg\" width=\"450\" height=\"324\" \/><\/p>\n<p>1.3 Valores de color 15<br \/>\n1.3.1 RGB 15<br \/>\n1.3.2 CMYK 15<br \/>\n1.3.3 Convertir valores CMYK a RGB 15<br \/>\n1.3.4 Hexadecimal 16<\/p>\n<p>1.4 El ojo humano 17<br \/>\n1.4.1 La c\u00e1mara perfecta 17<br \/>\n1.4.2 Sensores digitales 17<br \/>\n1.4.3 Captaci\u00f3n y visi\u00f3n del color 19<\/p>\n<p>1.5 Color y modulaci\u00f3n del color 20<br \/>\n1.5.1 Tono 20<br \/>\n1.5.2 Saturaci\u00f3n 20<br \/>\n1.5.3 Luminosidad 20<br \/>\n1.5.4 Sistema HSB 21<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" alt=\"calibrar el monitor\" src=\"http:\/\/www.microgamma.com\/calibracion_perfilacion_monitores\/2012\/llibre_2013_07.jpg\" width=\"450\" height=\"324\" \/><\/p>\n<p>CAP\u00cdTULO 2<br \/>\nReproducci\u00f3n del color<br \/>\n2.1 Bits por p\u00edxel 23<br \/>\n2.1.1 Tipos de im\u00e1genes 23<br \/>\n2.1.2 P\u00edxel y resoluci\u00f3n 24<br \/>\n2.1.3 Profundidad de tono 25<br \/>\n2.1.4 Las im\u00e1genes de 16 bit 26<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" alt=\"calibrar el monitor\" src=\"http:\/\/www.microgamma.com\/calibracion_perfilacion_monitores\/2012\/llibre_2013_08.jpg\" width=\"450\" height=\"324\" \/><\/p>\n<p>2.2 Los canales de color 27<br \/>\n2.2.1. Reacci\u00f3n de la luz al incidir sobre una<br \/>\nsuperficie coloreada 27<br \/>\n2.2.2. Proceso de generaci\u00f3n de los<br \/>\ncanales de color 27<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" alt=\"calibracion de monitores\" src=\"http:\/\/www.microgamma.com\/calibracion_perfilacion_monitores\/2012\/llibre_2013_09.jpg\" width=\"450\" height=\"324\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>2.3 La imagen impresa tramada 28<br \/>\n2.3.1 Caracter\u00edsticas de la trama peri\u00f3dica 28<br \/>\n2.3.2 Caracter\u00edsticas de la trama estoc\u00e1stica 29<br \/>\n2.3.3 Ganancia de punto 30<br \/>\n2.3.4 Compensaci\u00f3n de la ganancia de punto 30<br \/>\n2.3.5 Gamas Euroscale, SWOP y Toyo 31<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" alt=\"calibracion de monitores\" src=\"http:\/\/www.microgamma.com\/calibracion_perfilacion_monitores\/2012\/llibre_2013_10.jpg\" width=\"450\" height=\"324\" \/><\/p>\n<p>2.4 Ajustes de color en la imagen 31<br \/>\n2.4.1 Equilibrio de color 31<br \/>\n2.4.2 Reducci\u00f3n de color 32<\/p>\n<p>&nbsp;<\/p>\n<p>CAP\u00cdTULO 3<br \/>\nControl del color<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" alt=\"calibracion de monitores\" src=\"http:\/\/www.microgamma.com\/calibracion_perfilacion_monitores\/2012\/llibre_2013_11.jpg\" width=\"450\" height=\"324\" \/><\/p>\n<p>3.1 Metamerismo 35<br \/>\n3.1.1 CRI 36<br \/>\n3.2 Estandarizaci\u00f3n 37<br \/>\n3.3 La sala de trabajo 38<br \/>\n3.4 Planificaci\u00f3n de la iluminaci\u00f3n 40<br \/>\n3.5 Temperatura de color 41<br \/>\n3.5.1 El cuerpo negro 41<br \/>\n3.6 La Comisi\u00f3n Internacional de la<br \/>\nIluminaci\u00f3n (CIE) 42<br \/>\n3.6.1 CIE Yxy 42<br \/>\n3.6.2 CIE Lab 42<br \/>\n3.6.3 Iluminantes estandarizados 43<br \/>\n3.6.4 Delta E (\u2206E) 44<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" alt=\"calibracion de monitores\" src=\"http:\/\/www.microgamma.com\/calibracion_perfilacion_monitores\/2012\/llibre_2013_12.jpg\" width=\"450\" height=\"324\" \/><\/p>\n<p>3.7 Espacios de color 45<br \/>\n3.7.1 sRGB 45<br \/>\n3.7.2 Adobe RGB 45<br \/>\n3.7.3 eciRGB 46<br \/>\n3.7.4 NCS 46<br \/>\n3.7.5 Munsell 47<br \/>\n3.8 Gu\u00edas de tonos 48<br \/>\n3.9 Introducci\u00f3n a la gesti\u00f3n del color 50<br \/>\n3.9.1 Perfil de color ICC 50<br \/>\n3.9.2 Calibraci\u00f3n y linearizaci\u00f3n 50<br \/>\n3.9.3 Perfiles ICC versi\u00f3n 2 y 4 50<br \/>\n3.9.4 Ajuste entre perfiles 50<br \/>\n3.10 Gesti\u00f3n del color en navegadores Web 52<br \/>\n3.11 Perfiles de monitor sRGB y Adobe RGB 54<br \/>\n3.12 Tabla general 58<br \/>\n3.13 Calibraci\u00f3n de la captaci\u00f3n: la c\u00e1mara 60<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" alt=\"calibracion de monitores\" src=\"http:\/\/www.microgamma.com\/calibracion_perfilacion_monitores\/2012\/llibre_2013_13.jpg\" width=\"450\" height=\"324\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" alt=\"calibracion de monitores\" src=\"http:\/\/www.microgamma.com\/calibracion_perfilacion_monitores\/2012\/llibre_2013_14.jpg\" width=\"450\" height=\"324\" \/><\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" alt=\"calibracion de monitores\" src=\"http:\/\/www.microgamma.com\/calibracion_perfilacion_monitores\/2012\/llibre_2013_16.jpg\" width=\"450\" height=\"324\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>PARTE 2<\/p>\n<p>CAP\u00cdTULO 4<br \/>\nEstructura, componentes y controles de los monitores<\/p>\n<p>4.1. Especificaciones, t\u00e9rminos habituales 64<br \/>\n4.2. Uniformidad 65<br \/>\n4.3. Sistemas de iluminaci\u00f3n de los paneles 68<br \/>\n4.4. Tipos de paneles 70<br \/>\n4.4.1. Twisted nematic TN 70<br \/>\n4.4.2. Vertical alignment VA 70<br \/>\n4.4.3. In-plane switching IPS 70<br \/>\n4.5. La tabla LUT del monitor 72<br \/>\n4.6. Salida de 10 bits y paneles de 10 bits 74<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" alt=\"calibracion de monitores\" src=\"http:\/\/www.microgamma.com\/calibracion_perfilacion_monitores\/2012\/llibre_2013_15.jpg\" width=\"450\" height=\"324\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" alt=\"calibracion de monitores\" src=\"http:\/\/www.microgamma.com\/calibracion_perfilacion_monitores\/2012\/llibre_2013_17.jpg\" width=\"450\" height=\"324\" \/><\/p>\n<p>4.7 Valor gamma 76<br \/>\n4.8 Punto blanco, temperatura de color 78<br \/>\n4.9 Adaptaci\u00f3n crom\u00e1tica 80<br \/>\n4.10 Contraste 82<br \/>\n4.11 Brillo o luminancia 83<br \/>\n4.12 Herramientas de saturaci\u00f3n y tono 84<br \/>\n4.13 Trabajar con varias pantallas 86<\/p>\n<p>&nbsp;<\/p>\n<p>4.14 Limpieza de la pantalla 87<br \/>\n4.15 Resoluci\u00f3n de la pantalla 88<br \/>\n4.16 Ajustes complementarios 89<br \/>\n4.17 Viseras para el monitor 90<br \/>\n4.18 Conexiones del monitor 91<\/p>\n<p>CAP\u00cdTULO 5<br \/>\nMedios para la calibraci\u00f3n<\/p>\n<p>5.1 Im\u00e1genes de control o verficiaci\u00f3n 94<br \/>\n5.2 ColorChecker 95<br \/>\n5.3 Color\u00edmetros y espectrofot\u00f3metros 96<br \/>\n5.4 Programas para la calibraci\u00f3n 97<\/p>\n<p>&nbsp;<\/p>\n<p>CAP\u00cdTULO 6<br \/>\nCalibraci\u00f3n y perfilaci\u00f3n<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" alt=\"calibracion de monitores\" src=\"http:\/\/www.microgamma.com\/calibracion_perfilacion_monitores\/2012\/llibre_2013_18.jpg\" width=\"450\" height=\"324\" \/><\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" alt=\"calibracion de monitores\" src=\"http:\/\/www.microgamma.com\/calibracion_perfilacion_monitores\/2012\/llibre_2013_19.jpg\" width=\"450\" height=\"324\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Advertencias 99<br \/>\n6.1 Calibrando con Spyder4Elite 100<br \/>\n6.2 Calibrando con Spyder4PRO 108<br \/>\n6.3 Familia i1Display PRO 110<br \/>\n6.4 Calibrando con i1Display Pro 111<br \/>\n6.5 Calibrando con ColorMunki Display 116<br \/>\n6.6 ColorMunki Photo\/Design 120<br \/>\n6.7 BasICColor Display, calibraci\u00f3n h\u00edbrida 124<br \/>\n6.8 Argyll CMS + dispcalGUI 124<br \/>\n6.9 Calibraci\u00f3n por hardware 125<br \/>\n6.10 EIZO ColorNavigator 126<br \/>\n6.11 SpectraView Profiler\/BasicColor 132<br \/>\n6.12 Blue Eye PRO 137<br \/>\n6.13 Calibradores integrados 138<br \/>\n6.14 Certificaciones 139<br \/>\n6.14.1 Fogra 139<br \/>\n6.14.2 UGRA 140<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" alt=\"calibracion de monitores\" src=\"http:\/\/www.microgamma.com\/calibracion_perfilacion_monitores\/2012\/llibre_2013_20.jpg\" width=\"450\" height=\"324\" \/><\/p>\n<p>Fuentes y agradecimientos 142<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ya tenemos disponible la nueva edici\u00f3n del libro \u00abCalibraci\u00f3n y perfilaci\u00f3n de monitores\u00bb &nbsp; http:\/\/www.microgamma.com\/calibracion_perfilacion_monitores\/calibracion_monitores_nueva.php &nbsp; Introducci\u00f3n PARTE 1 CAP\u00cdTULO 1 Teor\u00eda del color 1.1. El espectro electromagn\u00e9tico 11 1.1.1 Longitud de onda 11 1.1.2 Espectro visible 12 1.1.3 Gr\u00e1ficas espectrofotom\u00e9tricas 12 1.1.4 Fotometr\u00eda 12 1.2 El color 13 1.2.1 Color emitido: S\u00edntesis aditiva (RGB) [&hellip;]<\/p>\n","protected":false},"author":32,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"site-container-style":"default","site-container-layout":"default","site-sidebar-layout":"default","disable-article-header":"default","disable-site-header":"default","disable-site-footer":"default","disable-content-area-spacing":"default","footnotes":""},"categories":[392],"tags":[474,409,475,1021,1256,676,1257,1285,1215,383,431,741,742,1258,430],"class_list":["post-3483","post","type-post","status-publish","format-standard","hentry","category-calibrarelmonitor","tag-calibracion-de-monitores","tag-calibracion-monitores","tag-calibrar-el-monitor","tag-calibrar-monitor-con-colornavigator","tag-calibrar-monitor-eye-one-3-como-usar","tag-calibrar-monitores","tag-como-calibrar-el-monitor","tag-disseny-igualada","tag-fotografia-alta-calidad-cs6-pdf","tag-i1display-pro","tag-libro-calibracion-monitores","tag-manual-de-instrucciones-del-calibrador-i1-display","tag-manual-de-instrucciones-del-calibrador-spyder","tag-problema-calibrar-monitor","tag-spyder4elite"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.monitor-para-fotografia.com\/index.php\/wp-json\/wp\/v2\/posts\/3483","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.monitor-para-fotografia.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.monitor-para-fotografia.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.monitor-para-fotografia.com\/index.php\/wp-json\/wp\/v2\/users\/32"}],"replies":[{"embeddable":true,"href":"https:\/\/www.monitor-para-fotografia.com\/index.php\/wp-json\/wp\/v2\/comments?post=3483"}],"version-history":[{"count":0,"href":"https:\/\/www.monitor-para-fotografia.com\/index.php\/wp-json\/wp\/v2\/posts\/3483\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.monitor-para-fotografia.com\/index.php\/wp-json\/wp\/v2\/media?parent=3483"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.monitor-para-fotografia.com\/index.php\/wp-json\/wp\/v2\/categories?post=3483"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.monitor-para-fotografia.com\/index.php\/wp-json\/wp\/v2\/tags?post=3483"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}