{"id":961,"date":"2010-03-09T22:52:15","date_gmt":"2010-03-09T21:52:15","guid":{"rendered":"http:\/\/www.microgamma.es\/blog\/?p=961"},"modified":"2021-04-13T11:05:26","modified_gmt":"2021-04-13T09:05:26","slug":"coloredge-cg241w","status":"publish","type":"post","link":"https:\/\/www.monitor-para-fotografia.com\/index.php\/2010\/03\/coloredge-cg241w\/","title":{"rendered":"ColorEdge CG241W"},"content":{"rendered":"<p>Reincorporamos este excelente monitor, que no hab\u00edamos retirado del todo. El CG241W se mantendr\u00e1 aun durante bastante tiempo como una alternativa m\u00e1s econ\u00f3mica al CG243W. A parte de la diferencia econ\u00f3mica el CG241W tiene unos tonos menos saturados que el CG243W y un panel S-PVA que posee un negro m\u00e1s profundo que los paneles IPS. El CG241W es casi un standard entre mucho fot\u00f3grafos de moda e industriales.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone\" src=\"http:\/\/www.microgamma.com\/eizo\/images\/eizo_241_640.jpg\" alt=\"\" width=\"507\" height=\"232\" \/><\/p>\n<p>Una de las principales diferencias del CG243W es su sistema de salida de 10 bit para conexiones Diplay Port, que tecnol\u00f3gicamente es muy avanzado pero que en la mayor\u00eda de los equipos actuales no se llega a utilizar ya que montan salidas DVI. Los usuarios podr\u00e1n elegir entre dos modelos del m\u00e1ximo nivel que comparten la mayor\u00eda de sus tecnolog\u00edas m\u00e1s importantes, calibraci\u00f3n autom\u00e1tica por hardware, sistema de uniformidad DUE, cobertura de los principales modos de color, etc.<\/p>\n<h5>Certificado GRACoL Grade #1 de IDEAlliance<\/h5>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.eizo.com\/global\/products\/coloredge\/cg241w\/images\/images.jpg\" alt=\"\" width=\"99\" height=\"98\" align=\"left\" \/>Este monitor en uso combinado con el software Adobe Acrobat 8 Professional forma un sistema de monitor de pruebas (proofing) certificado como GRACoL Grade #1 por IDEAlliance. Con el extendido uso del software Adobe Acrobat 8 Profesional, este sistema ofrece a las compa\u00f1\u00edas de premedia y a las empresas de preprensa un ahorro considerable respecto a los sistemas de monitores de pruebas (proofing) convencionales, los cuales requieren la compra de un paquete de software de pruebas del vendedor del sistema.<\/p>\n<p>(IDEAlliance (International Digital Enterprise Alliance, alianza internacional de empresas digitales) es una organizaci\u00f3n sin \u00e1nimo de lucro que ocupa una posici\u00f3n l\u00edder en tecnolog\u00edas de la informaci\u00f3n y publicaci\u00f3n desde 1966.)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Reincorporamos este excelente monitor, que no hab\u00edamos retirado del todo. El CG241W se mantendr\u00e1 aun durante bastante tiempo como una alternativa m\u00e1s econ\u00f3mica al CG243W. A parte de la diferencia econ\u00f3mica el CG241W tiene unos tonos menos saturados que el CG243W y un panel S-PVA que posee un negro m\u00e1s profundo que los paneles IPS. [&hellip;]<\/p>\n","protected":false},"author":32,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"site-container-style":"default","site-container-layout":"default","site-sidebar-layout":"default","disable-article-header":"default","disable-site-header":"default","disable-site-footer":"default","disable-content-area-spacing":"default","footnotes":""},"categories":[189],"tags":[264,103,2636,1654,256],"class_list":["post-961","post","type-post","status-publish","format-standard","hentry","category-coloredge-eizo-equipo-2","tag-cg241","tag-coloredge","tag-eizo","tag-eizo-cg241w","tag-eye-one"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.monitor-para-fotografia.com\/index.php\/wp-json\/wp\/v2\/posts\/961","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.monitor-para-fotografia.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.monitor-para-fotografia.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.monitor-para-fotografia.com\/index.php\/wp-json\/wp\/v2\/users\/32"}],"replies":[{"embeddable":true,"href":"https:\/\/www.monitor-para-fotografia.com\/index.php\/wp-json\/wp\/v2\/comments?post=961"}],"version-history":[{"count":0,"href":"https:\/\/www.monitor-para-fotografia.com\/index.php\/wp-json\/wp\/v2\/posts\/961\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.monitor-para-fotografia.com\/index.php\/wp-json\/wp\/v2\/media?parent=961"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.monitor-para-fotografia.com\/index.php\/wp-json\/wp\/v2\/categories?post=961"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.monitor-para-fotografia.com\/index.php\/wp-json\/wp\/v2\/tags?post=961"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}